{"id":3524,"date":"2026-05-21T14:02:50","date_gmt":"2026-05-21T13:02:50","guid":{"rendered":"https:\/\/aliance-mobilier.fr\/salon\/serviciz\/"},"modified":"2026-08-29T09:23:34","modified_gmt":"2026-08-29T08:23:34","slug":"serviciz","status":"publish","type":"salon","link":"https:\/\/aliance-mobilier.fr\/en_us\/salon\/serviciz\/","title":{"rendered":"SERVICIZ"},"parent":0,"template":"","class_list":["post-3524","salon","type-salon","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SERVICIZ - Aliance mobilier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aliance-mobilier.fr\/en_us\/salon\/serviciz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERVICIZ - Aliance mobilier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aliance-mobilier.fr\/en_us\/salon\/serviciz\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliance mobilier\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-29T08:23:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/salon\\\/serviciz\\\/\",\"url\":\"https:\\\/\\\/aliance-mobilier.fr\\\/salon\\\/serviciz\\\/\",\"name\":\"SERVICIZ - Aliance mobilier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/#website\"},\"datePublished\":\"2026-05-21T13:02:50+00:00\",\"dateModified\":\"2026-08-29T08:23:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/salon\\\/serviciz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aliance-mobilier.fr\\\/salon\\\/serviciz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/salon\\\/serviciz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aliance-mobilier.fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SERVICIZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/#website\",\"url\":\"https:\\\/\\\/aliance-mobilier.fr\\\/\",\"name\":\"Aliance mobilier\",\"description\":\"Location de mobilier \u00e9v\u00e9nementiel\",\"publisher\":{\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aliance-mobilier.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/#organization\",\"name\":\"Aliance mobilier\",\"url\":\"https:\\\/\\\/aliance-mobilier.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aliance-mobilier.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/aliance-svg-3.svg\",\"contentUrl\":\"https:\\\/\\\/aliance-mobilier.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/aliance-svg-3.svg\",\"width\":348,\"height\":34,\"caption\":\"Aliance mobilier\"},\"image\":{\"@id\":\"https:\\\/\\\/aliance-mobilier.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SERVICIZ - Aliance mobilier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aliance-mobilier.fr\/en_us\/salon\/serviciz\/","og_locale":"en_US","og_type":"article","og_title":"SERVICIZ - Aliance mobilier","og_url":"https:\/\/aliance-mobilier.fr\/en_us\/salon\/serviciz\/","og_site_name":"Aliance mobilier","article_modified_time":"2026-08-29T08:23:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aliance-mobilier.fr\/salon\/serviciz\/","url":"https:\/\/aliance-mobilier.fr\/salon\/serviciz\/","name":"SERVICIZ - Aliance mobilier","isPartOf":{"@id":"https:\/\/aliance-mobilier.fr\/#website"},"datePublished":"2026-05-21T13:02:50+00:00","dateModified":"2026-08-29T08:23:34+00:00","breadcrumb":{"@id":"https:\/\/aliance-mobilier.fr\/salon\/serviciz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aliance-mobilier.fr\/salon\/serviciz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aliance-mobilier.fr\/salon\/serviciz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aliance-mobilier.fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"SERVICIZ"}]},{"@type":"WebSite","@id":"https:\/\/aliance-mobilier.fr\/#website","url":"https:\/\/aliance-mobilier.fr\/","name":"Aliance mobilier","description":"Location de mobilier \u00e9v\u00e9nementiel","publisher":{"@id":"https:\/\/aliance-mobilier.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aliance-mobilier.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aliance-mobilier.fr\/#organization","name":"Aliance mobilier","url":"https:\/\/aliance-mobilier.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aliance-mobilier.fr\/#\/schema\/logo\/image\/","url":"https:\/\/aliance-mobilier.fr\/wp-content\/uploads\/2026\/02\/aliance-svg-3.svg","contentUrl":"https:\/\/aliance-mobilier.fr\/wp-content\/uploads\/2026\/02\/aliance-svg-3.svg","width":348,"height":34,"caption":"Aliance mobilier"},"image":{"@id":"https:\/\/aliance-mobilier.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aliance-mobilier.fr\/en_us\/wp-json\/wp\/v2\/salon\/3524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliance-mobilier.fr\/en_us\/wp-json\/wp\/v2\/salon"}],"about":[{"href":"https:\/\/aliance-mobilier.fr\/en_us\/wp-json\/wp\/v2\/types\/salon"}],"wp:attachment":[{"href":"https:\/\/aliance-mobilier.fr\/en_us\/wp-json\/wp\/v2\/media?parent=3524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}